{"id":4295,"date":"2015-12-04T17:32:43","date_gmt":"2015-12-04T17:32:43","guid":{"rendered":"http:\/\/documentation.feed.biz\/?page_id=4295&#038;lang=fr"},"modified":"2017-03-10T18:49:05","modified_gmt":"2017-03-10T18:49:05","slug":"documentation-ebay","status":"publish","type":"page","link":"https:\/\/documentation.feed.biz\/fr\/documentation-ebay\/","title":{"rendered":"eBay"},"content":{"rendered":"<p><span class=\"path\"><a title=\"Accueil\" href=\"http:\/\/documentation.feed.biz\/?lang=fr\">Accueil<\/a> &gt; <a title=\"Documentation eBay\" href=\"https:\/\/documentation.feed.biz\/fr\/documentation-ebay\/\">Documentation eBay<\/a><\/span><br \/>\n&nbsp;<\/p>\n<ul class=\"m-t15 p-l20 list-unstyled\">\n<li><a href=\"https:\/\/documentation.feed.biz\/fr\/configuration\/\">Configuration<\/a><\/li>\n<li><a href=\"https:\/\/documentation.feed.biz\/fr\/ebay-options-des-offres\/\">Options des Offres<\/a><\/li>\n<li><a href=\"https:\/\/documentation.feed.biz\/fr\/taches-actions\/\">Op\u00e9rations<\/a><\/li>\n<li><a href=\"https:\/\/documentation.feed.biz\/fr\/journal-dimportation-des-commandes\/\">Historique\u00a0des Commandes<\/a><\/li>\n<li><a href=\"https:\/\/documentation.feed.biz\/fr\/rapports\/\">Rapports<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Accueil &gt; Documentation eBay &nbsp; Configuration Options des Offres Op\u00e9rations Historique\u00a0des Commandes Rapports<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-4295","page","type-page","status-publish","hentry","category-ebay"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>eBay - Documentation | Feed.Biz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/documentation.feed.biz\/documentation-ebay\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"eBay - Documentation | Feed.Biz\" \/>\n<meta property=\"og:description\" content=\"Accueil &gt; Documentation eBay &nbsp; Configuration Options des Offres Op\u00e9rations Historique\u00a0des Commandes Rapports\" \/>\n<meta property=\"og:url\" content=\"https:\/\/documentation.feed.biz\/fr\/documentation-ebay\/\" \/>\n<meta property=\"og:site_name\" content=\"Documentation | Feed.Biz\" \/>\n<meta property=\"article:modified_time\" content=\"2017-03-10T18:49:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/documentation.feed.biz\/fr\/documentation-ebay\/\",\"url\":\"https:\/\/documentation.feed.biz\/fr\/documentation-ebay\/\",\"name\":\"eBay - Documentation | Feed.Biz\",\"isPartOf\":{\"@id\":\"https:\/\/documentation.feed.biz\/#website\"},\"datePublished\":\"2015-12-04T17:32:43+00:00\",\"dateModified\":\"2017-03-10T18:49:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/documentation.feed.biz\/fr\/documentation-ebay\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/documentation.feed.biz\/fr\/documentation-ebay\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/documentation.feed.biz\/fr\/documentation-ebay\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/documentation.feed.biz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"eBay\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/documentation.feed.biz\/#website\",\"url\":\"https:\/\/documentation.feed.biz\/\",\"name\":\"Documentation | Feed.Biz\",\"description\":\"Documentation\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/documentation.feed.biz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"eBay - Documentation | Feed.Biz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/documentation.feed.biz\/documentation-ebay\/","og_locale":"en_US","og_type":"article","og_title":"eBay - Documentation | Feed.Biz","og_description":"Accueil &gt; Documentation eBay &nbsp; Configuration Options des Offres Op\u00e9rations Historique\u00a0des Commandes Rapports","og_url":"https:\/\/documentation.feed.biz\/fr\/documentation-ebay\/","og_site_name":"Documentation | Feed.Biz","article_modified_time":"2017-03-10T18:49:05+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/documentation.feed.biz\/fr\/documentation-ebay\/","url":"https:\/\/documentation.feed.biz\/fr\/documentation-ebay\/","name":"eBay - Documentation | Feed.Biz","isPartOf":{"@id":"https:\/\/documentation.feed.biz\/#website"},"datePublished":"2015-12-04T17:32:43+00:00","dateModified":"2017-03-10T18:49:05+00:00","breadcrumb":{"@id":"https:\/\/documentation.feed.biz\/fr\/documentation-ebay\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/documentation.feed.biz\/fr\/documentation-ebay\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/documentation.feed.biz\/fr\/documentation-ebay\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/documentation.feed.biz\/"},{"@type":"ListItem","position":2,"name":"eBay"}]},{"@type":"WebSite","@id":"https:\/\/documentation.feed.biz\/#website","url":"https:\/\/documentation.feed.biz\/","name":"Documentation | Feed.Biz","description":"Documentation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/documentation.feed.biz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/documentation.feed.biz\/fr\/wp-json\/wp\/v2\/pages\/4295\/"}],"collection":[{"href":"https:\/\/documentation.feed.biz\/fr\/wp-json\/wp\/v2\/pages\/"}],"about":[{"href":"https:\/\/documentation.feed.biz\/fr\/wp-json\/wp\/v2\/types\/page\/"}],"author":[{"embeddable":true,"href":"https:\/\/documentation.feed.biz\/fr\/wp-json\/wp\/v2\/users\/4\/"}],"replies":[{"embeddable":true,"href":"https:\/\/documentation.feed.biz\/fr\/wp-json\/wp\/v2\/comments\/?post=4295"}],"version-history":[{"count":12,"href":"https:\/\/documentation.feed.biz\/fr\/wp-json\/wp\/v2\/pages\/4295\/revisions\/"}],"predecessor-version":[{"id":6536,"href":"https:\/\/documentation.feed.biz\/fr\/wp-json\/wp\/v2\/pages\/4295\/revisions\/6536\/"}],"wp:attachment":[{"href":"https:\/\/documentation.feed.biz\/fr\/wp-json\/wp\/v2\/media\/?parent=4295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/documentation.feed.biz\/fr\/wp-json\/wp\/v2\/categories\/?post=4295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/documentation.feed.biz\/fr\/wp-json\/wp\/v2\/tags\/?post=4295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}