{"id":4,"name":"Imen Rahal","url":"","description":"","link":"https:\/\/documentation.feed.biz\/author\/imen\/","slug":"imen","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/5a6d7f41353f9ad437bd38ee0935375b?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/5a6d7f41353f9ad437bd38ee0935375b?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/5a6d7f41353f9ad437bd38ee0935375b?s=96&d=mm&r=g"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Imen Rahal, Author at Documentation | Feed.Biz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/documentation.feed.biz\/author\/imen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Imen Rahal, Author at Documentation | Feed.Biz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/documentation.feed.biz\/author\/imen\/\" \/>\n<meta property=\"og:site_name\" content=\"Documentation | Feed.Biz\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/5a6d7f41353f9ad437bd38ee0935375b?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\/\/documentation.feed.biz\/author\/imen\/\",\"url\":\"https:\/\/documentation.feed.biz\/author\/imen\/\",\"name\":\"Imen Rahal, Author at Documentation | Feed.Biz\",\"isPartOf\":{\"@id\":\"https:\/\/documentation.feed.biz\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/documentation.feed.biz\/author\/imen\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/documentation.feed.biz\/author\/imen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/documentation.feed.biz\/author\/imen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/documentation.feed.biz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives for Imen Rahal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/documentation.feed.biz\/#website\",\"url\":\"https:\/\/documentation.feed.biz\/\",\"name\":\"Documentation | Feed.Biz\",\"description\":\"Documentation\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/documentation.feed.biz\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/documentation.feed.biz\/#\/schema\/person\/02bb57056e3fddda7fc8ca8baa938124\",\"name\":\"Imen Rahal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/documentation.feed.biz\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5a6d7f41353f9ad437bd38ee0935375b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5a6d7f41353f9ad437bd38ee0935375b?s=96&d=mm&r=g\",\"caption\":\"Imen Rahal\"},\"mainEntityOfPage\":{\"@id\":\"https:\/\/documentation.feed.biz\/author\/imen\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Imen Rahal, Author at Documentation | Feed.Biz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/documentation.feed.biz\/author\/imen\/","og_locale":"en_US","og_type":"profile","og_title":"Imen Rahal, Author at Documentation | Feed.Biz","og_url":"https:\/\/documentation.feed.biz\/author\/imen\/","og_site_name":"Documentation | Feed.Biz","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/5a6d7f41353f9ad437bd38ee0935375b?s=500&d=mm&r=g"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/documentation.feed.biz\/author\/imen\/","url":"https:\/\/documentation.feed.biz\/author\/imen\/","name":"Imen Rahal, Author at Documentation | Feed.Biz","isPartOf":{"@id":"https:\/\/documentation.feed.biz\/#website"},"breadcrumb":{"@id":"https:\/\/documentation.feed.biz\/author\/imen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/documentation.feed.biz\/author\/imen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/documentation.feed.biz\/author\/imen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/documentation.feed.biz\/"},{"@type":"ListItem","position":2,"name":"Archives for Imen Rahal"}]},{"@type":"WebSite","@id":"https:\/\/documentation.feed.biz\/#website","url":"https:\/\/documentation.feed.biz\/","name":"Documentation | Feed.Biz","description":"Documentation","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/documentation.feed.biz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/documentation.feed.biz\/#\/schema\/person\/02bb57056e3fddda7fc8ca8baa938124","name":"Imen Rahal","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/documentation.feed.biz\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5a6d7f41353f9ad437bd38ee0935375b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5a6d7f41353f9ad437bd38ee0935375b?s=96&d=mm&r=g","caption":"Imen Rahal"},"mainEntityOfPage":{"@id":"https:\/\/documentation.feed.biz\/author\/imen\/"}}]}},"_links":{"self":[{"href":"https:\/\/documentation.feed.biz\/fr\/wp-json\/wp\/v2\/users\/4\/"}],"collection":[{"href":"https:\/\/documentation.feed.biz\/fr\/wp-json\/wp\/v2\/users\/"}]}}